{"id":97,"count":0,"description":"","link":"https:\/\/elamusspa.test.code-lab.it\/et\/tootekategooria\/elamus-spa\/","name":"Elamus SPA","slug":"elamus-spa","taxonomy":"product_cat","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/elamusspa.test.code-lab.it\/et\/wp-json\/wp\/v2\/product_cat\/97"}],"collection":[{"href":"https:\/\/elamusspa.test.code-lab.it\/et\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/elamusspa.test.code-lab.it\/et\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/elamusspa.test.code-lab.it\/et\/wp-json\/wp\/v2\/product?product_cat=97"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}